{"id":22898,"date":"2026-05-13T02:03:07","date_gmt":"2026-05-13T02:03:07","guid":{"rendered":"https:\/\/semanariochilecitotv.com.ar\/?p=22898"},"modified":"2026-05-13T02:03:07","modified_gmt":"2026-05-13T02:03:07","slug":"continua-el-bacheo-en-chilecito","status":"publish","type":"post","link":"https:\/\/semanariochilecitotv.com.ar\/index.php\/2026\/05\/13\/continua-el-bacheo-en-chilecito\/","title":{"rendered":"Contin\u00faa el bacheo en Chilecito"},"content":{"rendered":"<p>El Municipio, a trav\u00e9s de la Secretar\u00eda de Obras P\u00fablicas, contin\u00faa desarrollando tareas de bacheo en distintos sectores de nuestra ciudad, con el objetivo de mejorar la transitabilidad y brindar mayor seguridad a vecinos y conductores.<!--more--><\/p>\n<p>En esta oportunidad, los trabajos se realizan utilizando una nueva emulsi\u00f3n asf\u00e1ltica, que permite optimizar las tareas y garantizar una mejor respuesta en la reparaci\u00f3n de las calles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Municipio, a trav\u00e9s de la Secretar\u00eda de Obras P\u00fablicas, contin\u00faa desarrollando tareas de bacheo en distintos sectores de nuestra ciudad, con el objetivo de mejorar la transitabilidad y brindar mayor seguridad a vecinos y conductores.<\/p>\n","protected":false},"author":1,"featured_media":22899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-22898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=22898"}],"version-history":[{"count":1,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22898\/revisions"}],"predecessor-version":[{"id":22900,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/22898\/revisions\/22900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/22899"}],"wp:attachment":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=22898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=22898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=22898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}