{"id":21607,"date":"2026-02-10T01:38:31","date_gmt":"2026-02-10T01:38:31","guid":{"rendered":"https:\/\/semanariochilecitotv.com.ar\/?p=21607"},"modified":"2026-02-10T01:38:31","modified_gmt":"2026-02-10T01:38:31","slug":"emiten-alerta-preventiva-por-lluvias-y-vientos","status":"publish","type":"post","link":"https:\/\/semanariochilecitotv.com.ar\/index.php\/2026\/02\/10\/emiten-alerta-preventiva-por-lluvias-y-vientos\/","title":{"rendered":"Emiten alerta preventiva por lluvias y vientos"},"content":{"rendered":"<p>El Sistema Integrado de Alerta Temprana (SIAT) emiti\u00f3 un alerta amarilla por la probable ocurrencia de lluvias aisladas y vientos para distintas zonas del territorio provincial.<!--more--><\/p>\n<p>El reporte del SIAT precis\u00f3 que el alerta por lluvias rige para los departamentos Vinchina, General Lamadrid, General Felipe Varela, Famatina, Chilecito, San Blas de los Sauces, Arauco, Castro Barros, Sanagasta y Capital.<\/p>\n<p>En tanto la probabilidad de vientos alcanza a los departamentos Vinchina, General Lamadrid, Famatina, San Blas de los Sauces y Arauco. De acuerdo al reporte, los vientos llegar\u00edan con r\u00e1fagas que podr\u00edan alcanzar los 60 kil\u00f3metros por hora en la zona de cordillera mientras que para los departamentos mencionados las r\u00e1fagas podr\u00edan oscilar entre los 60 y los 75 kil\u00f3metros por hora.<\/p>\n<p>El alerta amarilla rige desde la noche de este lunes y para la madrugada del martes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Sistema Integrado de Alerta Temprana (SIAT) emiti\u00f3 un alerta amarilla por la probable ocurrencia de lluvias aisladas y vientos para distintas zonas del territorio provincial.<\/p>\n","protected":false},"author":1,"featured_media":21608,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-21607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provinciales"],"_links":{"self":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21607"}],"version-history":[{"count":1,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21607\/revisions"}],"predecessor-version":[{"id":21609,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21607\/revisions\/21609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/21608"}],"wp:attachment":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}