{"id":21598,"date":"2026-02-09T14:35:01","date_gmt":"2026-02-09T14:35:01","guid":{"rendered":"https:\/\/semanariochilecitotv.com.ar\/?p=21598"},"modified":"2026-02-09T14:35:01","modified_gmt":"2026-02-09T14:35:01","slug":"comienzan-los-corsos-oficiales-2026","status":"publish","type":"post","link":"https:\/\/semanariochilecitotv.com.ar\/index.php\/2026\/02\/09\/comienzan-los-corsos-oficiales-2026\/","title":{"rendered":"Comienzan los Corsos Oficiales 2026"},"content":{"rendered":"<p>Desde este lunes 9 y durante cinco noches, viviremos a pleno los tan esperados Corsos Oficiales 2026<!--more--><\/p>\n<p>La cita ser\u00e1 en la Plaza de la Cultura Cacique Coronilla, a partir de las 21 horas, donde el color, la m\u00fasica y la alegr\u00eda ser\u00e1n protagonistas de cada jornada.<\/p>\n<p>Desfilar\u00e1n disfraces mayores y menores, comparsas infantiles y de adultos, y las tradicionales carrozas, llenando cada noche de brillo, creatividad y esp\u00edritu festivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde este lunes 9 y durante cinco noches, viviremos a pleno los tan esperados Corsos Oficiales 2026<\/p>\n","protected":false},"author":1,"featured_media":21599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-21598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=21598"}],"version-history":[{"count":1,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21598\/revisions"}],"predecessor-version":[{"id":21600,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/21598\/revisions\/21600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/21599"}],"wp:attachment":[{"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=21598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=21598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semanariochilecitotv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=21598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}